{"id":10798,"date":"2023-04-06T09:50:00","date_gmt":"2023-04-06T13:50:00","guid":{"rendered":"http:\/\/3.96.229.193\/?p=10798"},"modified":"2026-08-19T10:16:18","modified_gmt":"2026-08-19T14:16:18","slug":"sanexen-remporte-le-premier-contrat-dans-son-genre-aupres-de-waste-connections-pour-lutter-contre-les-pfas","status":"publish","type":"post","link":"https:\/\/sanexen.com\/fr\/2023\/04\/06\/sanexen-remporte-le-premier-contrat-dans-son-genre-aupres-de-waste-connections-pour-lutter-contre-les-pfas\/","title":{"rendered":"SANEXEN remporte le premier contrat dans son genre aupr\u00e8s de Waste Connections pour lutter contre les PFAS"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Montr\u00e9al, Qu\u00e9bec, le 6 avril 2023<\/strong> \u2013 ALTRA | SANEXEN, chef de file en mati\u00e8re de solutions pour l\u2019environnement et l'eau, a annonc\u00e9 aujourd'hui qu'elle a obtenu un contrat de Waste Connections pour fournir la premi\u00e8re solution continue de r\u00e9habilitation des PFAS \u00e0 grande \u00e9chelle dans l'industrie de la gestion des sites d\u2019enfouissement et des d\u00e9chets industriels. Ce contrat, le premier dans son genre, vise \u00e0 atteindre un niveau garanti d'\u00e9limination des PFAS dans les lixiviats contamin\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les PFAS, ou substances per- et polyfluoroalkyl\u00e9es, sont un groupe de produits chimiques de synth\u00e8se, aussi connus sous le nom de \u00ab&nbsp;produits chimiques \u00e9ternels&nbsp;\u00bb, qui ont \u00e9t\u00e9 fabriqu\u00e9s pour une utilisation dans une vaste gamme de produits industriels et de biens de consommation. Lorsque ces produits arrivent en fin de vie et sont mis au rebut, ils finissent par se retrouver dans les sites d\u2019enfouissement. Les recherches ont d\u00e9montr\u00e9 que les PFAS sont devenus omnipr\u00e9sents dans l'environnement et pr\u00e9sentent un risque pour la sant\u00e9 lorsqu'ils s'accumulent dans l'organisme, d'o\u00f9 la n\u00e9cessit\u00e9 de d\u00e9truire ou de s\u00e9questrer ces contaminants en toute s\u00e9curit\u00e9, tout en limitant les sous-produits nocifs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ALTRA Solution PFAS offre aux exploitants de sites d\u2019enfouissement l'approche la plus compl\u00e8te et la plus \u00e9conomique pour r\u00e9duire la contamination des PFAS dans les lixiviats et les eaux us\u00e9es. La solution d\u2019ALTRA conjugue la puissance de sa technologie exclusive de fractionnement par moussage \u00e0 des unit\u00e9s modulaires tr\u00e8s performantes qui fonctionnent en mode continu pour traiter de grands volumes de contaminants dans l'eau. Dans le cadre de ce projet novateur, ALTRA | SANEXEN fournira et exploitera ses unit\u00e9s modulaires dans les sites d\u2019enfouissement de Waste Connections \u00e0 Rosemount et Rich Valley, dans le Minnesota, pendant les dix prochaines ann\u00e9es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab&nbsp;Waste Connections est heureuse de s'associer \u00e0 ALTRA | SANEXEN pour r\u00e9duire la concentration des PFAS dans le lixiviat g\u00e9n\u00e9r\u00e9 dans nos sites d\u2019enfouissement&nbsp;\u00bb, a d\u00e9clar\u00e9 Kurt Shaner, vice-pr\u00e9sident, ing\u00e9nierie et d\u00e9veloppement durable. \u00ab&nbsp;Les PFAS sont couramment utilis\u00e9s dans de nombreux produits m\u00e9nagers et commerciaux qui se transforment ensuite en d\u00e9chets d\u00e9pos\u00e9s dans nos sites d\u2019enfouissement. En tant que destinataire de ces d\u00e9chets contenant des PFAS, nous nous effor\u00e7ons de s\u00e9questrer correctement autant de PFAS pr\u00e9sents dans ces d\u00e9chets que possible, et pour tous les sous-produits de sites d\u2019enfouissement contenant des PFAS que nous ne sommes pas en mesure de s\u00e9questrer, nous nous engageons \u00e0 les traiter de mani\u00e8re \u00e0 r\u00e9duire leur pr\u00e9sence&nbsp;\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab&nbsp;ALTRA Solution PFAS est l'aboutissement d'ann\u00e9es de d\u00e9veloppement, d'essais pilotes approfondis dans les conditions les plus complexes et il s\u2019agit de la meilleure fa\u00e7on d'\u00e9liminer une quantit\u00e9 importante de PFAS des lixiviats avec la confiance que seules des ann\u00e9es d'exp\u00e9rience sur le terrain permettent d'acqu\u00e9rir&nbsp;\u00bb, a d\u00e9clar\u00e9 Martin Bureau, vice-pr\u00e9sident, innovation, ALTRA&nbsp;|&nbsp;SANEXEN et responsable des PFAS. Nous sommes tr\u00e8s enthousiastes \u00e0 l'id\u00e9e de fournir notre technologie \u00e9prouv\u00e9e pour aider dans le traitement des lixiviats de sites d\u2019enfouissement&nbsp;\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab&nbsp;Waste Connections est \u00e0 l'avant-garde en mati\u00e8re de durabilit\u00e9 dans la gestion des d\u00e9chets et nous sommes honor\u00e9s de prendre part au prochain chapitre, alors qu'elle continue \u00e0 faire preuve de leadership environnemental dans l'industrie de l'enfouissement&nbsp;\u00bb, a renforc\u00e9 Jean-Fran\u00e7ois Bolduc, pr\u00e9sident d'ALTRA&nbsp;|&nbsp;SANEXEN. \u00ab&nbsp;L'\u00e9quipe d'experts d'ALTRA partage l'engagement de Waste Connections \u00e0 r\u00e9soudre les d\u00e9fis environnementaux auxquels font face les march\u00e9s de l'enfouissement et de la gestion des d\u00e9chets industriels. Nous sommes ravis de nous associer \u00e0 des clients tels que Waste Connections afin d'avoir un impact durable sur les g\u00e9n\u00e9rations futures&nbsp;\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pour plus d\u2019information:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Marie-Chantal Savoy<br>Vice-pr\u00e9sidente, strat\u00e9gie et communications<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Montr\u00e9al, Qu\u00e9bec, le 6 avril 2023 \u2013 ALTRA | SANEXEN, chef de file en mati\u00e8re de solutions pour l\u2019environnement et l&rsquo;eau, a annonc\u00e9 aujourd&rsquo;hui qu&rsquo;elle a obtenu un contrat de Waste Connections pour fournir la premi\u00e8re solution continue de r\u00e9habilitation des PFAS \u00e0 grande \u00e9chelle dans l&rsquo;industrie de la gestion des sites d\u2019enfouissement et des [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":10796,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[29,31],"tags":[],"class_list":["post-10798","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-communiques","category-projets-gagnes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SANEXEN remporte le premier contrat dans son genre aupr\u00e8s de Waste Connections pour lutter contre les PFAS | SANEXEN<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sanexen.com\/fr\/2023\/04\/06\/sanexen-remporte-le-premier-contrat-dans-son-genre-aupres-de-waste-connections-pour-lutter-contre-les-pfas\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SANEXEN remporte le premier contrat dans son genre aupr\u00e8s de Waste Connections pour lutter contre les PFAS | SANEXEN\" \/>\n<meta property=\"og:description\" content=\"Montr\u00e9al, Qu\u00e9bec, le 6 avril 2023 \u2013 ALTRA | SANEXEN, chef de file en mati\u00e8re de solutions pour l\u2019environnement et l&rsquo;eau, a annonc\u00e9 aujourd&rsquo;hui qu&rsquo;elle a obtenu un contrat de Waste Connections pour fournir la premi\u00e8re solution continue de r\u00e9habilitation des PFAS \u00e0 grande \u00e9chelle dans l&rsquo;industrie de la gestion des sites d\u2019enfouissement et des [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sanexen.com\/fr\/2023\/04\/06\/sanexen-remporte-le-premier-contrat-dans-son-genre-aupres-de-waste-connections-pour-lutter-contre-les-pfas\/\" \/>\n<meta property=\"og:site_name\" content=\"SANEXEN\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sanexen.env\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-06T13:50:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-19T14:16:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sanexen.com\/wp-content\/uploads\/2023\/04\/Image2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2545\" \/>\n\t<meta property=\"og:image:height\" content=\"1417\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marilyne Thomas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sanexen_env\" \/>\n<meta name=\"twitter:site\" content=\"@sanexen_env\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marilyne Thomas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sanexen.com\\\/fr\\\/2023\\\/04\\\/06\\\/sanexen-remporte-le-premier-contrat-dans-son-genre-aupres-de-waste-connections-pour-lutter-contre-les-pfas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sanexen.com\\\/fr\\\/2023\\\/04\\\/06\\\/sanexen-remporte-le-premier-contrat-dans-son-genre-aupres-de-waste-connections-pour-lutter-contre-les-pfas\\\/\"},\"author\":{\"name\":\"Marilyne Thomas\",\"@id\":\"https:\\\/\\\/sanexen.com\\\/fr\\\/#\\\/schema\\\/person\\\/3c52368b62a30550e023fd775e22b537\"},\"headline\":\"SANEXEN remporte le premier contrat dans son genre aupr\u00e8s de Waste Connections pour lutter contre les PFAS\",\"datePublished\":\"2023-04-06T13:50:00+00:00\",\"dateModified\":\"2026-08-19T14:16:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sanexen.com\\\/fr\\\/2023\\\/04\\\/06\\\/sanexen-remporte-le-premier-contrat-dans-son-genre-aupres-de-waste-connections-pour-lutter-contre-les-pfas\\\/\"},\"wordCount\":705,\"publisher\":{\"@id\":\"https:\\\/\\\/sanexen.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/sanexen.com\\\/fr\\\/2023\\\/04\\\/06\\\/sanexen-remporte-le-premier-contrat-dans-son-genre-aupres-de-waste-connections-pour-lutter-contre-les-pfas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sanexen.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Image2.jpg\",\"articleSection\":[\"Communiqu\u00e9s\",\"Projets gagn\u00e9s\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sanexen.com\\\/fr\\\/2023\\\/04\\\/06\\\/sanexen-remporte-le-premier-contrat-dans-son-genre-aupres-de-waste-connections-pour-lutter-contre-les-pfas\\\/\",\"url\":\"https:\\\/\\\/sanexen.com\\\/fr\\\/2023\\\/04\\\/06\\\/sanexen-remporte-le-premier-contrat-dans-son-genre-aupres-de-waste-connections-pour-lutter-contre-les-pfas\\\/\",\"name\":\"SANEXEN remporte le premier contrat dans son genre aupr\u00e8s de Waste Connections pour lutter contre les PFAS | SANEXEN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sanexen.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sanexen.com\\\/fr\\\/2023\\\/04\\\/06\\\/sanexen-remporte-le-premier-contrat-dans-son-genre-aupres-de-waste-connections-pour-lutter-contre-les-pfas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sanexen.com\\\/fr\\\/2023\\\/04\\\/06\\\/sanexen-remporte-le-premier-contrat-dans-son-genre-aupres-de-waste-connections-pour-lutter-contre-les-pfas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sanexen.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Image2.jpg\",\"datePublished\":\"2023-04-06T13:50:00+00:00\",\"dateModified\":\"2026-08-19T14:16:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sanexen.com\\\/fr\\\/2023\\\/04\\\/06\\\/sanexen-remporte-le-premier-contrat-dans-son-genre-aupres-de-waste-connections-pour-lutter-contre-les-pfas\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sanexen.com\\\/fr\\\/2023\\\/04\\\/06\\\/sanexen-remporte-le-premier-contrat-dans-son-genre-aupres-de-waste-connections-pour-lutter-contre-les-pfas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sanexen.com\\\/fr\\\/2023\\\/04\\\/06\\\/sanexen-remporte-le-premier-contrat-dans-son-genre-aupres-de-waste-connections-pour-lutter-contre-les-pfas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sanexen.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Image2.jpg\",\"contentUrl\":\"https:\\\/\\\/sanexen.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Image2.jpg\",\"width\":2545,\"height\":1417},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sanexen.com\\\/fr\\\/2023\\\/04\\\/06\\\/sanexen-remporte-le-premier-contrat-dans-son-genre-aupres-de-waste-connections-pour-lutter-contre-les-pfas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sanexen.com\\\/fr\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SANEXEN remporte le premier contrat dans son genre aupr\u00e8s de Waste Connections pour lutter contre les PFAS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sanexen.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/sanexen.com\\\/fr\\\/\",\"name\":\"SANEXEN\",\"description\":\"Driving innovation in environmental, water, climate change and circular economy solutions.\",\"publisher\":{\"@id\":\"https:\\\/\\\/sanexen.com\\\/fr\\\/#organization\"},\"alternateName\":\"Sanexen Services environnementaux\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sanexen.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sanexen.com\\\/fr\\\/#organization\",\"name\":\"SANEXEN\",\"alternateName\":\"SANEXEN Services environnementaux\",\"url\":\"https:\\\/\\\/sanexen.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sanexen.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sanexen.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/SNX-logo-696X696.png\",\"contentUrl\":\"https:\\\/\\\/sanexen.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/SNX-logo-696X696.png\",\"width\":696,\"height\":696,\"caption\":\"SANEXEN\"},\"image\":{\"@id\":\"https:\\\/\\\/sanexen.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sanexen.env\\\/\",\"https:\\\/\\\/x.com\\\/sanexen_env\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/sanexen-env\",\"https:\\\/\\\/www.youtube.com\\\/@sanexen-env\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sanexen.com\\\/fr\\\/#\\\/schema\\\/person\\\/3c52368b62a30550e023fd775e22b537\",\"name\":\"Marilyne Thomas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/60c9d972f84577233acece740ecda8c054bc8f02e2fab9dcbff2b5c83d7af764?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/60c9d972f84577233acece740ecda8c054bc8f02e2fab9dcbff2b5c83d7af764?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/60c9d972f84577233acece740ecda8c054bc8f02e2fab9dcbff2b5c83d7af764?s=96&d=mm&r=g\",\"caption\":\"Marilyne Thomas\"},\"url\":\"https:\\\/\\\/sanexen.com\\\/fr\\\/author\\\/mthomassanexen-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SANEXEN remporte le premier contrat dans son genre aupr\u00e8s de Waste Connections pour lutter contre les PFAS | SANEXEN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sanexen.com\/fr\/2023\/04\/06\/sanexen-remporte-le-premier-contrat-dans-son-genre-aupres-de-waste-connections-pour-lutter-contre-les-pfas\/","og_locale":"fr_FR","og_type":"article","og_title":"SANEXEN remporte le premier contrat dans son genre aupr\u00e8s de Waste Connections pour lutter contre les PFAS | SANEXEN","og_description":"Montr\u00e9al, Qu\u00e9bec, le 6 avril 2023 \u2013 ALTRA | SANEXEN, chef de file en mati\u00e8re de solutions pour l\u2019environnement et l&rsquo;eau, a annonc\u00e9 aujourd&rsquo;hui qu&rsquo;elle a obtenu un contrat de Waste Connections pour fournir la premi\u00e8re solution continue de r\u00e9habilitation des PFAS \u00e0 grande \u00e9chelle dans l&rsquo;industrie de la gestion des sites d\u2019enfouissement et des [&hellip;]","og_url":"https:\/\/sanexen.com\/fr\/2023\/04\/06\/sanexen-remporte-le-premier-contrat-dans-son-genre-aupres-de-waste-connections-pour-lutter-contre-les-pfas\/","og_site_name":"SANEXEN","article_publisher":"https:\/\/www.facebook.com\/sanexen.env\/","article_published_time":"2023-04-06T13:50:00+00:00","article_modified_time":"2026-08-19T14:16:18+00:00","og_image":[{"width":2545,"height":1417,"url":"https:\/\/sanexen.com\/wp-content\/uploads\/2023\/04\/Image2.jpg","type":"image\/jpeg"}],"author":"Marilyne Thomas","twitter_card":"summary_large_image","twitter_creator":"@sanexen_env","twitter_site":"@sanexen_env","twitter_misc":{"\u00c9crit par":"Marilyne Thomas","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sanexen.com\/fr\/2023\/04\/06\/sanexen-remporte-le-premier-contrat-dans-son-genre-aupres-de-waste-connections-pour-lutter-contre-les-pfas\/#article","isPartOf":{"@id":"https:\/\/sanexen.com\/fr\/2023\/04\/06\/sanexen-remporte-le-premier-contrat-dans-son-genre-aupres-de-waste-connections-pour-lutter-contre-les-pfas\/"},"author":{"name":"Marilyne Thomas","@id":"https:\/\/sanexen.com\/fr\/#\/schema\/person\/3c52368b62a30550e023fd775e22b537"},"headline":"SANEXEN remporte le premier contrat dans son genre aupr\u00e8s de Waste Connections pour lutter contre les PFAS","datePublished":"2023-04-06T13:50:00+00:00","dateModified":"2026-08-19T14:16:18+00:00","mainEntityOfPage":{"@id":"https:\/\/sanexen.com\/fr\/2023\/04\/06\/sanexen-remporte-le-premier-contrat-dans-son-genre-aupres-de-waste-connections-pour-lutter-contre-les-pfas\/"},"wordCount":705,"publisher":{"@id":"https:\/\/sanexen.com\/fr\/#organization"},"image":{"@id":"https:\/\/sanexen.com\/fr\/2023\/04\/06\/sanexen-remporte-le-premier-contrat-dans-son-genre-aupres-de-waste-connections-pour-lutter-contre-les-pfas\/#primaryimage"},"thumbnailUrl":"https:\/\/sanexen.com\/wp-content\/uploads\/2023\/04\/Image2.jpg","articleSection":["Communiqu\u00e9s","Projets gagn\u00e9s"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/sanexen.com\/fr\/2023\/04\/06\/sanexen-remporte-le-premier-contrat-dans-son-genre-aupres-de-waste-connections-pour-lutter-contre-les-pfas\/","url":"https:\/\/sanexen.com\/fr\/2023\/04\/06\/sanexen-remporte-le-premier-contrat-dans-son-genre-aupres-de-waste-connections-pour-lutter-contre-les-pfas\/","name":"SANEXEN remporte le premier contrat dans son genre aupr\u00e8s de Waste Connections pour lutter contre les PFAS | SANEXEN","isPartOf":{"@id":"https:\/\/sanexen.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sanexen.com\/fr\/2023\/04\/06\/sanexen-remporte-le-premier-contrat-dans-son-genre-aupres-de-waste-connections-pour-lutter-contre-les-pfas\/#primaryimage"},"image":{"@id":"https:\/\/sanexen.com\/fr\/2023\/04\/06\/sanexen-remporte-le-premier-contrat-dans-son-genre-aupres-de-waste-connections-pour-lutter-contre-les-pfas\/#primaryimage"},"thumbnailUrl":"https:\/\/sanexen.com\/wp-content\/uploads\/2023\/04\/Image2.jpg","datePublished":"2023-04-06T13:50:00+00:00","dateModified":"2026-08-19T14:16:18+00:00","breadcrumb":{"@id":"https:\/\/sanexen.com\/fr\/2023\/04\/06\/sanexen-remporte-le-premier-contrat-dans-son-genre-aupres-de-waste-connections-pour-lutter-contre-les-pfas\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sanexen.com\/fr\/2023\/04\/06\/sanexen-remporte-le-premier-contrat-dans-son-genre-aupres-de-waste-connections-pour-lutter-contre-les-pfas\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sanexen.com\/fr\/2023\/04\/06\/sanexen-remporte-le-premier-contrat-dans-son-genre-aupres-de-waste-connections-pour-lutter-contre-les-pfas\/#primaryimage","url":"https:\/\/sanexen.com\/wp-content\/uploads\/2023\/04\/Image2.jpg","contentUrl":"https:\/\/sanexen.com\/wp-content\/uploads\/2023\/04\/Image2.jpg","width":2545,"height":1417},{"@type":"BreadcrumbList","@id":"https:\/\/sanexen.com\/fr\/2023\/04\/06\/sanexen-remporte-le-premier-contrat-dans-son-genre-aupres-de-waste-connections-pour-lutter-contre-les-pfas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sanexen.com\/fr\/home\/"},{"@type":"ListItem","position":2,"name":"SANEXEN remporte le premier contrat dans son genre aupr\u00e8s de Waste Connections pour lutter contre les PFAS"}]},{"@type":"WebSite","@id":"https:\/\/sanexen.com\/fr\/#website","url":"https:\/\/sanexen.com\/fr\/","name":"SANEXEN","description":"Driving innovation in environmental, water, climate change and circular economy solutions.","publisher":{"@id":"https:\/\/sanexen.com\/fr\/#organization"},"alternateName":"Sanexen Services environnementaux","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sanexen.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/sanexen.com\/fr\/#organization","name":"SANEXEN","alternateName":"SANEXEN Services environnementaux","url":"https:\/\/sanexen.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sanexen.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/sanexen.com\/wp-content\/uploads\/2025\/11\/SNX-logo-696X696.png","contentUrl":"https:\/\/sanexen.com\/wp-content\/uploads\/2025\/11\/SNX-logo-696X696.png","width":696,"height":696,"caption":"SANEXEN"},"image":{"@id":"https:\/\/sanexen.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sanexen.env\/","https:\/\/x.com\/sanexen_env","https:\/\/www.linkedin.com\/company\/sanexen-env","https:\/\/www.youtube.com\/@sanexen-env"]},{"@type":"Person","@id":"https:\/\/sanexen.com\/fr\/#\/schema\/person\/3c52368b62a30550e023fd775e22b537","name":"Marilyne Thomas","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/60c9d972f84577233acece740ecda8c054bc8f02e2fab9dcbff2b5c83d7af764?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/60c9d972f84577233acece740ecda8c054bc8f02e2fab9dcbff2b5c83d7af764?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/60c9d972f84577233acece740ecda8c054bc8f02e2fab9dcbff2b5c83d7af764?s=96&d=mm&r=g","caption":"Marilyne Thomas"},"url":"https:\/\/sanexen.com\/fr\/author\/mthomassanexen-com\/"}]}},"_links":{"self":[{"href":"https:\/\/sanexen.com\/fr\/wp-json\/wp\/v2\/posts\/10798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sanexen.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sanexen.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sanexen.com\/fr\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/sanexen.com\/fr\/wp-json\/wp\/v2\/comments?post=10798"}],"version-history":[{"count":3,"href":"https:\/\/sanexen.com\/fr\/wp-json\/wp\/v2\/posts\/10798\/revisions"}],"predecessor-version":[{"id":23467,"href":"https:\/\/sanexen.com\/fr\/wp-json\/wp\/v2\/posts\/10798\/revisions\/23467"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sanexen.com\/fr\/wp-json\/wp\/v2\/media\/10796"}],"wp:attachment":[{"href":"https:\/\/sanexen.com\/fr\/wp-json\/wp\/v2\/media?parent=10798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sanexen.com\/fr\/wp-json\/wp\/v2\/categories?post=10798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sanexen.com\/fr\/wp-json\/wp\/v2\/tags?post=10798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}